{"id":57102,"date":"2020-09-25T11:45:09","date_gmt":"2020-09-25T09:45:09","guid":{"rendered":"https:\/\/www.right2city.org\/?post_type=news&#038;p=57102"},"modified":"2020-09-25T11:45:09","modified_gmt":"2020-09-25T09:45:09","slug":"live-international-zero-evictions","status":"publish","type":"news","link":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/","title":{"rendered":"Live International Z\u00e9ro Evictions"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-56671\" src=\"https:\/\/www.right2city.org\/wp-content\/uploads\/2020\/08\/ES-Cero-Desalojo-724x1024.png\" alt=\"\" width=\"482\" height=\"682\" \/><\/p>\n<p>Le 4 septembre, des institutions et des mouvements sociaux ont organis\u00e9 un \u00e9v\u00e9nement international en ligne <strong>contre les expulsions et les renvois.<\/strong> L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 retransmis en direct par Zoom, avec Balakrishnan Rajagopal, le rapporteur sp\u00e9cial des Nations unies sur le droit \u00e0 un logement ad\u00e9quat, et des dirigeants de mouvements sociaux du Mexique, d&rsquo;Italie, des \u00c9tats-Unis, d&rsquo;Inde, d&rsquo;Afrique du Sud, d&rsquo;Espagne, et un public de plus de 600 participants.<\/p>\n<p>L&rsquo;\u00e9mission a \u00e9t\u00e9 traduite simultan\u00e9ment en anglais, en espagnol et en portugais.<\/p>\n<p>L&rsquo;initiative fait partie de la <strong>campagne \u00ab\u00a0Z\u00e9ro Expulsion\u00a0\u00bb, cr\u00e9\u00e9e dans le but de faire pression sur le pouvoir public avec le soutien de la population, pour mettre fin aux expulsions et aux renvois, qu&rsquo;ils soient le r\u00e9sultat d&rsquo;une initiative priv\u00e9e ou publique, et qui ont pour but de d\u00e9placer des familles et des communaut\u00e9s urbaines ou rurales.<\/strong><br \/>\nL&rsquo;articulation rassemble \u00e9galement des centaines de mouvements de la campagne et de la ville.<\/p>\n<p>L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 divis\u00e9 en deux blocs, le premier comprenant les t\u00e9moignages de dirigeants de mouvements de diff\u00e9rentes villes du monde.<br \/>\nCette premi\u00e8re partie a compt\u00e9 avec la pr\u00e9sentation de :<br \/>\n&#8211; Maria Silvia Emanuelli, de la Coalition internationale Habitat (HIC) au Mexique,<br \/>\n&#8211; Cesare Ottolini, de l&rsquo;Alliance internationale des habitants (IAI) en Italie<br \/>\n&#8211; Cea Weaver, repr\u00e9sentant de Cancel the Rent, des \u00c9tats-Unis,<br \/>\n&#8211; Shivani Chaudhry, du R\u00e9seau des droits au logement et \u00e0 la terre en Inde<br \/>\n&#8211; Luc\u00eda Delgado Ramisa, de la Plateforme des personnes affect\u00e9es par les hypoth\u00e8ques (PAH) en Espagne, et<br \/>\n&#8211; Mpho Raboeane, de l&rsquo;organisation Ndifuna Ukwazi en Afrique du Sud<\/p>\n<p>Le deuxi\u00e8me bloc a \u00e9t\u00e9 pr\u00e9sent\u00e9 par Nelson Saule J\u00fanior, coordinateur de la <strong>Plateforme Globale pour le Droit \u00e0 la Ville<\/strong> et L\u00facia Moraes, de la Plateforme br\u00e9silienne pour les droits de l&rsquo;homme (<strong>DHESCA Br\u00e9sil<\/strong>). Des repr\u00e9sentants de mouvements sociaux de toutes les r\u00e9gions du Br\u00e9sil \u00e9taient \u00e9galement pr\u00e9sents \u00e0 l&rsquo;\u00e9v\u00e9nement, pr\u00e9sentant des photos d&rsquo;expulsions dans le pays.<\/p>\n<p>En plus, Benedito Barbosa, de la Centrale des mouvements populaires, a remis au rapporteur de l&rsquo;ONU le rapport de d\u00e9nonciation pr\u00e9par\u00e9 par les organisations membres de la campagne.<br \/>\nLe rapport s&rsquo;est bas\u00e9 sur les<strong> informations recueillies par les institutions elles-m\u00eames, entre le 1er mars et le 31 ao\u00fbt, par le biais de d\u00e9nonciations, de formulaires en ligne et de la base de donn\u00e9es de l&rsquo;Observatoire des d\u00e9m\u00e9nagements et des d\u00e9fenseurs publics.<\/strong><br \/>\nDans ce rapport, plus de <strong>30 cas d&rsquo;expulsion ont \u00e9t\u00e9 identifi\u00e9s au Br\u00e9sil au cours de la p\u00e9riode analys\u00e9e, touchant plus de 6 373 familles.<\/strong><br \/>\n<strong>Environ 47% des cas se sont produits en Amazonie, avec 3000 expulsions recens\u00e9es.<\/strong><br \/>\n<strong>S\u00e3o Paulo<\/strong> compte \u00e9galement un grand nombre de familles touch\u00e9es, repr\u00e9sentant <strong>1681 expulsions, soit 26% du total des cas.<\/strong><br \/>\nOutre ces \u00c9tats, des expulsions ont \u00e9galement \u00e9t\u00e9 constat\u00e9es dans les \u00c9tats suivants : Minas Gerais, Pernambuco, Sergipe, Roraima, Paran\u00e1, Santa Catarina, Maranh\u00e3o, Rio Grande do Norte, Goi\u00e1s, Rio de Janeiro et Rio Grande do Sul.<\/p>\n<p>La discussion a \u00e9t\u00e9 anim\u00e9e par la professeure Raquel Rolnik, coordinatrice de LabCidade (USP) et ancienne Rapporteur des Nations unies.<\/p>\n<p>Le rapporteur sp\u00e9cial des Nations unies sur le droit \u00e0 un logement ad\u00e9quat, Balakrishnan Rajagopal, \u00e9tait charg\u00e9 de la pr\u00e9sentation de la r\u00e9union et, comme il l&rsquo;a conclu dans son discours final, si d&rsquo;une part nous traversons de multiples crises intersectionnelles, d&rsquo;autre part, les luttes pour le monde sont \u00e9galement interconnect\u00e9es et <strong>la solidarit\u00e9 est la cl\u00e9 pour surmonter les d\u00e9fis auxquels nous sommes confront\u00e9s en tant que soci\u00e9t\u00e9, en particulier ceux qui impliquent des violations. du droit au logement, \u00e0 la terre et \u00e0 la ville<\/strong><\/p>\n","protected":false},"featured_media":56671,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":""},"categories":[],"themes":[164],"agendas_globales":[],"class_list":["post-57102","news","type-news","status-publish","has-post-thumbnail","hentry","themes-fonctions-sociales-remplies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Live International Z\u00e9ro Evictions - Right to the city<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Live International Z\u00e9ro Evictions - Right to the city\" \/>\n<meta property=\"og:description\" content=\"Le 4 septembre, des institutions et des mouvements sociaux ont organis\u00e9 un \u00e9v\u00e9nement international en ligne contre les expulsions et les renvois. L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 retransmis en direct par Zoom, avec Balakrishnan Rajagopal, le rapporteur sp\u00e9cial des Nations unies sur le droit \u00e0 un logement ad\u00e9quat, et des dirigeants de mouvements sociaux du Mexique, d&rsquo;Italie, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/\" \/>\n<meta property=\"og:site_name\" content=\"Right to the city\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.right2city.org\/wp-content\/uploads\/2020\/08\/ES-Cero-Desalojo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1414\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/news\\\/live-international-zero-evictions\\\/\",\"url\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/news\\\/live-international-zero-evictions\\\/\",\"name\":\"Live International Z\u00e9ro Evictions - Right to the city\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/news\\\/live-international-zero-evictions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/news\\\/live-international-zero-evictions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.right2city.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/ES-Cero-Desalojo.png\",\"datePublished\":\"2020-09-25T09:45:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/news\\\/live-international-zero-evictions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.right2city.org\\\/fr\\\/news\\\/live-international-zero-evictions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/news\\\/live-international-zero-evictions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.right2city.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/ES-Cero-Desalojo.png\",\"contentUrl\":\"https:\\\/\\\/www.right2city.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/ES-Cero-Desalojo.png\",\"width\":1414,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/news\\\/live-international-zero-evictions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Live International Z\u00e9ro Evictions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/\",\"name\":\"Right to the city\",\"description\":\"Global Platform for the Right to the City\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.right2city.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Live International Z\u00e9ro Evictions - Right to the city","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/","og_locale":"fr_FR","og_type":"article","og_title":"Live International Z\u00e9ro Evictions - Right to the city","og_description":"Le 4 septembre, des institutions et des mouvements sociaux ont organis\u00e9 un \u00e9v\u00e9nement international en ligne contre les expulsions et les renvois. L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 retransmis en direct par Zoom, avec Balakrishnan Rajagopal, le rapporteur sp\u00e9cial des Nations unies sur le droit \u00e0 un logement ad\u00e9quat, et des dirigeants de mouvements sociaux du Mexique, d&rsquo;Italie, [&hellip;]","og_url":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/","og_site_name":"Right to the city","og_image":[{"width":1414,"height":2000,"url":"https:\/\/www.right2city.org\/wp-content\/uploads\/2020\/08\/ES-Cero-Desalojo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/","url":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/","name":"Live International Z\u00e9ro Evictions - Right to the city","isPartOf":{"@id":"https:\/\/www.right2city.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/#primaryimage"},"image":{"@id":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/#primaryimage"},"thumbnailUrl":"https:\/\/www.right2city.org\/wp-content\/uploads\/2020\/08\/ES-Cero-Desalojo.png","datePublished":"2020-09-25T09:45:09+00:00","breadcrumb":{"@id":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/#primaryimage","url":"https:\/\/www.right2city.org\/wp-content\/uploads\/2020\/08\/ES-Cero-Desalojo.png","contentUrl":"https:\/\/www.right2city.org\/wp-content\/uploads\/2020\/08\/ES-Cero-Desalojo.png","width":1414,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/www.right2city.org\/fr\/news\/live-international-zero-evictions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.right2city.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/www.right2city.org\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Live International Z\u00e9ro Evictions"}]},{"@type":"WebSite","@id":"https:\/\/www.right2city.org\/fr\/#website","url":"https:\/\/www.right2city.org\/fr\/","name":"Right to the city","description":"Global Platform for the Right to the City","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.right2city.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.right2city.org\/fr\/wp-json\/wp\/v2\/news\/57102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.right2city.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.right2city.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.right2city.org\/fr\/wp-json\/wp\/v2\/media\/56671"}],"wp:attachment":[{"href":"https:\/\/www.right2city.org\/fr\/wp-json\/wp\/v2\/media?parent=57102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.right2city.org\/fr\/wp-json\/wp\/v2\/categories?post=57102"},{"taxonomy":"themes","embeddable":true,"href":"https:\/\/www.right2city.org\/fr\/wp-json\/wp\/v2\/themes?post=57102"},{"taxonomy":"agendas_globales","embeddable":true,"href":"https:\/\/www.right2city.org\/fr\/wp-json\/wp\/v2\/agendas_globales?post=57102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}